{"id":15916,"date":"2025-03-14T10:31:07","date_gmt":"2025-03-14T14:31:07","guid":{"rendered":"http:\/\/www.theadkx.org\/?p=15916"},"modified":"2025-03-17T09:06:48","modified_gmt":"2025-03-17T13:06:48","slug":"adkx-anuncia-los-galardonados-con-el-premio-harold-k-hochschild-2025-adirondack-foundation-y-cali-brooks","status":"publish","type":"post","link":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/","title":{"rendered":"La ADKX anuncia los galardonados con el Premio Harold K. Hochschild 2025 Fundaci\u00f3n Adirondack y Cali Brooks"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Lago Blue Mountain, NY<\/strong> <strong>\u2014<\/strong> The Adirondack Experience, The Museum on Blue Mountain Lake (ADKX) celebrar\u00e1 su gala ben\u00e9fica anual y la ceremonia de entrega del premio Harold K. Hochschild el s\u00e1bado 26 de julio, de 17.00 a 21.00 horas, bajo las estrellas en su museo en el coraz\u00f3n de las Adirondacks. Esta celebraci\u00f3n anual y recaudaci\u00f3n de fondos destaca el servicio de la organizaci\u00f3n a la comunidad de Adirondack, as\u00ed como honra al galardonado con el Premio Harold K. Hochschild. Este premio, que se concede anualmente a un galardonado diferente, est\u00e1 dedicado a la memoria del fundador del museo, cuya pasi\u00f3n por los Adirondacks, su gente y su medio ambiente le inspir\u00f3 para crear el museo y establecer la Agencia del Parque Adirondack (APA). Los galardonados de 2025 son la Fundaci\u00f3n Adirondack y el Director General y Presidente Cali Brooks.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La Fundaci\u00f3n Adirondack est\u00e1 formada por un grupo de compasivos solucionadores de problemas que trabajan para mejorar la vida de la gente de los Adirondacks a trav\u00e9s de la filantrop\u00eda. Trabajan para poner en contacto a donantes generosos con las causas que les preocupan en los lugares que aman. Es la mayor fundaci\u00f3n privada de la regi\u00f3n en la concesi\u00f3n de subvenciones y la que mejor conecta con la comunidad. Como \u00fanica fundaci\u00f3n comunitaria que presta servicios en toda la regi\u00f3n de Adirondack, se enorgullece de administrar una familia de fondos reunidos e invertidos conjuntamente para lograr el m\u00e1ximo impacto. La inversi\u00f3n colectiva de estos fondos les ha permitido conceder millones de d\u00f3lares junto con muchos donantes generosos desde su fundaci\u00f3n en 1997.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el principio, Cali Brooks, Directora Ejecutiva y Presidenta, ha sido la fuerza impulsora del enorme cambio positivo que la Fundaci\u00f3n ha generado en la regi\u00f3n de Adirondack. Durante su mandato, la dotaci\u00f3n de la Fundaci\u00f3n ha pasado de $2M a $100M, apoyando a cientos de organizaciones regionales sin \u00e1nimo de lucro con m\u00e1s de $80 millones en subvenciones y becas. La incre\u00edble canalizaci\u00f3n filantr\u00f3pica que Brooks ha ayudado a crear se ha convertido en el salvavidas de muchas personas en los Adirondacks. A lo largo del \u00faltimo cuarto de siglo, Brooks se ha convertido en uno de los principales actores del Parque Adirondack, remodelando gradualmente la Fundaci\u00f3n Adirondack y su capacidad para influir no s\u00f3lo en peque\u00f1os proyectos, sino tambi\u00e9n en proyectos de mayor envergadura.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u201cCali Brooks tiene una pasi\u00f3n sin igual por el Parque Adirondack y el bienestar de todos sus ciudadanos. S\u00e9 que Harold Hochschild habr\u00eda estado encantado de ver el impacto que la Fundaci\u00f3n est\u00e1 teniendo en los Adirondacks y su gente. Eso es lo que a \u00e9l le importaba tanto\u201d.\u201d <\/em>afirma Frances Beinecke, patrona honoraria de la ADKX.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas de sus iniciativas de mayor repercusi\u00f3n en la comunidad son la Alianza Adirondack Birth to Three, cuyo objetivo es ofrecer a los ni\u00f1os el mejor comienzo posible para que puedan convertirse en miembros sanos y pr\u00f3speros de la comunidad, y el Fondo para Necesidades Especiales y Urgentes, que proporciona recursos de respuesta que pueden utilizarse para ayudar a las comunidades y organizaciones sin \u00e1nimo de lucro de Adirondack en tiempos de crisis. El fondo ha ayudado a comunidades, empresas y particulares de los Adirondacks, incluyendo m\u00e1s de $2M en fondos de respuesta y recuperaci\u00f3n de COVID-19. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>\u201cLa ADKX quiere agradecer a Cali Brooks y a la Fundaci\u00f3n Adirondack su notable dedicaci\u00f3n para hacer de la regi\u00f3n de Adirondack un lugar mejor para vivir\u201d.\u201d <\/em>afirm\u00f3 el Director Ejecutivo, David Kahn. <em>\u201cEstamos deseando celebrarlas en la Gala de este a\u00f1o\u201d.\u201d<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Para comprar entradas para este evento o hacer una contribuci\u00f3n en honor de la Fundaci\u00f3n Adirondack y Cali Brooks visite el sitio web de ADKX <a href=\"https:\/\/www.theadkx.org\/es\/evento\/gala-benefica-y-premio-harold-k-hochschild\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>AQU\u00cd<\/strong><\/a><strong>.<\/strong><br><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\" id=\"h-about-adirondack-experience-the-museum-on-blue-mountain-lake\">Acerca de Adirondack Experience, el museo del lago Blue Mountain<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Adirondack Experience, The Museum on Blue Mountain Lake (ADKX), acreditado por la Alianza Americana de Museos, comparte la historia y la cultura de la regi\u00f3n de Adirondack a trav\u00e9s de exposiciones interactivas, actividades pr\u00e1cticas y colecciones culturalmente ricas en m\u00e1s de 24 edificios hist\u00f3ricos y contempor\u00e1neos en un campus de 121 acres en el coraz\u00f3n de los Adirondacks. El ADKX ofrece un amplio abanico de programas y actividades, como exposiciones especiales y permanentes, el museo de 19.000 pies cuadrados <em>La vida en los Adirondacks <\/em>exposici\u00f3n interactiva y nueva <em>Artistas e inspiraci\u00f3n en la naturaleza<\/em>, excursiones por senderos naturales y paseos en barca por Minnow Pond. El ADKX ofrece actividades diarias con artistas residentes, talleres, conferencias, paseos por la naturaleza, programas familiares y educativos, y eventos emblem\u00e1ticos como la Feria R\u00fastica, el FallFest y el Festival de Arte de Adirondack. El museo se financia en parte con donaciones del p\u00fablico en general, y una parte de las ayudas generales de funcionamiento son posibles gracias al Consejo de las Artes del Estado de Nueva York, con el apoyo de la Gobernadora Kathy Hochul y la Legislatura del Estado de Nueva York. Para m\u00e1s informaci\u00f3n, llame al 518-352-7311 o visite www.theADKX.org.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Contacto con los medios de comunicaci\u00f3n:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\">Adena Miller<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Medios para romper el hielo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:adena@breaktheicemedia.com\">adena@breaktheicemedia.com<\/a> \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C: 585-490-9437<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Adirondack <\/strong><strong>Experiencia Contacto:<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\">Tara Murphy<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Director de Marketing y Comunicaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/es\/tmurphy@theadkx.org\/\">tmurphy@theadkx.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O: 518-352-7311 ext. 182<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Descargue aqu\u00ed el comunicado completo<\/summary>\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/ADKX-Announces-the-2025-Harold-K.-Hochschild-Award-Recipients-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de ADKX anuncia los galardonados con el Premio Harold K. Hochschild 2025.\"><\/object><a id=\"wp-block-file--media-ac82641c-7223-43da-a3c4-458d00e36b00\" href=\"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/ADKX-Announces-the-2025-Harold-K.-Hochschild-Award-Recipients-1.pdf\">La ADKX anuncia los galardonados con el Premio Harold K. Hochschild 2025<\/a><a href=\"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/ADKX-Announces-the-2025-Harold-K.-Hochschild-Award-Recipients-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-ac82641c-7223-43da-a3c4-458d00e36b00\">Descargar<\/a><\/div>\n<\/details>","protected":false},"excerpt":{"rendered":"<p>Blue Mountain Lake, NY \u2014 The Adirondack Experience, The Museum on Blue Mountain Lake (ADKX) will be celebrating their annual Benefit Gala &amp; Harold K. Hochschild Award ceremony on Saturday, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":15919,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-15916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-room"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks | Adirondack Experience<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theadkx.org\/es\/adkx-anuncia-los-galardonados-con-el-premio-harold-k-hochschild-2025-adirondack-foundation-y-cali-brooks\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks\" \/>\n<meta property=\"og:description\" content=\"Blue Mountain Lake, NY \u2014 The Adirondack Experience, The Museum on Blue Mountain Lake (ADKX) will be celebrating their annual Benefit Gala &amp; Harold K.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theadkx.org\/es\/adkx-anuncia-los-galardonados-con-el-premio-harold-k-hochschild-2025-adirondack-foundation-y-cali-brooks\/\" \/>\n<meta property=\"og:site_name\" content=\"Adirondack Experience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/theADKX\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T14:31:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T13:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joe Dolan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@theadkx\" \/>\n<meta name=\"twitter:site\" content=\"@theadkx\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joe Dolan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/\"},\"author\":{\"name\":\"Joe Dolan\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/person\\\/57ece69aee53d2cc4ccd2b34e79256f4\"},\"headline\":\"ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks\",\"datePublished\":\"2025-03-14T14:31:07+00:00\",\"dateModified\":\"2025-03-17T13:06:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/\"},\"wordCount\":762,\"publisher\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg\",\"articleSection\":[\"Press Room\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/\",\"name\":\"ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks | Adirondack Experience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg\",\"datePublished\":\"2025-03-14T14:31:07+00:00\",\"dateModified\":\"2025-03-17T13:06:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg\",\"contentUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg\",\"width\":1080,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.theadkx.org\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#website\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/\",\"name\":\"Adirondack Experience\",\"description\":\"The Museum on Blue Mountain Lake\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.theadkx.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#organization\",\"name\":\"Adirondack Experience, The Museum on Blue Mountain Lake\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ADKX_LOGO.png\",\"contentUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ADKX_LOGO.png\",\"width\":440,\"height\":276,\"caption\":\"Adirondack Experience, The Museum on Blue Mountain Lake\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/theADKX\\\/\",\"https:\\\/\\\/x.com\\\/theadkx\",\"https:\\\/\\\/www.instagram.com\\\/theadkx\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AdirondackMuseum\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/person\\\/57ece69aee53d2cc4ccd2b34e79256f4\",\"name\":\"Joe Dolan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23846da25bfb5135b3880ceb8372db2eda4a9a1873d0d07e7a1bdea4d5562c5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23846da25bfb5135b3880ceb8372db2eda4a9a1873d0d07e7a1bdea4d5562c5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23846da25bfb5135b3880ceb8372db2eda4a9a1873d0d07e7a1bdea4d5562c5f?s=96&d=mm&r=g\",\"caption\":\"Joe Dolan\"},\"sameAs\":[\"https:\\\/\\\/www.theadkx.org\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ADKX anuncia los galardonados con el Premio Harold K. Hochschild 2025 Fundaci\u00f3n Adirondack y Cali Brooks | Adirondack Experience","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theadkx.org\/es\/adkx-anuncia-los-galardonados-con-el-premio-harold-k-hochschild-2025-adirondack-foundation-y-cali-brooks\/","og_locale":"es_ES","og_type":"article","og_title":"ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks","og_description":"Blue Mountain Lake, NY \u2014 The Adirondack Experience, The Museum on Blue Mountain Lake (ADKX) will be celebrating their annual Benefit Gala &amp; Harold K.","og_url":"https:\/\/www.theadkx.org\/es\/adkx-anuncia-los-galardonados-con-el-premio-harold-k-hochschild-2025-adirondack-foundation-y-cali-brooks\/","og_site_name":"Adirondack Experience","article_publisher":"https:\/\/www.facebook.com\/theADKX\/","article_published_time":"2025-03-14T14:31:07+00:00","article_modified_time":"2025-03-17T13:06:48+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg","type":"image\/jpeg"}],"author":"Joe Dolan","twitter_card":"summary_large_image","twitter_creator":"@theadkx","twitter_site":"@theadkx","twitter_misc":{"Escrito por":"Joe Dolan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/#article","isPartOf":{"@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/"},"author":{"name":"Joe Dolan","@id":"https:\/\/www.theadkx.org\/#\/schema\/person\/57ece69aee53d2cc4ccd2b34e79256f4"},"headline":"ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks","datePublished":"2025-03-14T14:31:07+00:00","dateModified":"2025-03-17T13:06:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/"},"wordCount":762,"publisher":{"@id":"https:\/\/www.theadkx.org\/#organization"},"image":{"@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/#primaryimage"},"thumbnailUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg","articleSection":["Press Room"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/","url":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/","name":"ADKX anuncia los galardonados con el Premio Harold K. Hochschild 2025 Fundaci\u00f3n Adirondack y Cali Brooks | Adirondack Experience","isPartOf":{"@id":"https:\/\/www.theadkx.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/#primaryimage"},"image":{"@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/#primaryimage"},"thumbnailUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg","datePublished":"2025-03-14T14:31:07+00:00","dateModified":"2025-03-17T13:06:48+00:00","breadcrumb":{"@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/#primaryimage","url":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg","contentUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2025\/03\/22b2ed2d-10d6-9513-a43b-32aa78ac754d.jpg","width":1080,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/www.theadkx.org\/es\/adkx-announces-the-2025-harold-k-hochschild-award-recipients-adirondack-foundation-and-cali-brooks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theadkx.org\/homepage\/"},{"@type":"ListItem","position":2,"name":"ADKX Announces the 2025 Harold K. Hochschild Award Recipients Adirondack Foundation and Cali Brooks"}]},{"@type":"WebSite","@id":"https:\/\/www.theadkx.org\/#website","url":"https:\/\/www.theadkx.org\/","name":"Experiencia Adirondack","description":"El Museo del Lago de la Monta\u00f1a Azul","publisher":{"@id":"https:\/\/www.theadkx.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theadkx.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.theadkx.org\/#organization","name":"Experiencia Adirondack, El Museo del Lago Blue Mountain","url":"https:\/\/www.theadkx.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.theadkx.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/03\/ADKX_LOGO.png","contentUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/03\/ADKX_LOGO.png","width":440,"height":276,"caption":"Adirondack Experience, The Museum on Blue Mountain Lake"},"image":{"@id":"https:\/\/www.theadkx.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/theADKX\/","https:\/\/x.com\/theadkx","https:\/\/www.instagram.com\/theadkx\/","https:\/\/www.youtube.com\/user\/AdirondackMuseum"]},{"@type":"Person","@id":"https:\/\/www.theadkx.org\/#\/schema\/person\/57ece69aee53d2cc4ccd2b34e79256f4","name":"Joe Dolan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23846da25bfb5135b3880ceb8372db2eda4a9a1873d0d07e7a1bdea4d5562c5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23846da25bfb5135b3880ceb8372db2eda4a9a1873d0d07e7a1bdea4d5562c5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23846da25bfb5135b3880ceb8372db2eda4a9a1873d0d07e7a1bdea4d5562c5f?s=96&d=mm&r=g","caption":"Joe Dolan"},"sameAs":["https:\/\/www.theadkx.org\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/posts\/15916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/comments?post=15916"}],"version-history":[{"count":4,"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/posts\/15916\/revisions"}],"predecessor-version":[{"id":15927,"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/posts\/15916\/revisions\/15927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/media\/15919"}],"wp:attachment":[{"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/media?parent=15916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/categories?post=15916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theadkx.org\/es\/wp-json\/wp\/v2\/tags?post=15916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}