{"id":927,"date":"2017-04-04T17:24:00","date_gmt":"2017-04-04T21:24:00","guid":{"rendered":"http:\/\/www.theadkx.org\/?p=927"},"modified":"2021-04-09T00:42:37","modified_gmt":"2021-04-09T04:42:37","slug":"la-naissance-des-parcs-a-mots-dans-les-adirondacks","status":"publish","type":"post","link":"https:\/\/www.theadkx.org\/fr\/the-birth-of-theme-parks-in-the-adirondacks\/","title":{"rendered":"La naissance des parcs \u00e0 th\u00e8me dans les Adirondacks"},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg\" alt=\"\" class=\"wp-image-928\" width=\"400\" height=\"253\" srcset=\"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg 800w, https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks-300x190.jpeg 300w, https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks-768x486.jpeg 768w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p>Le printemps dans le parc des Adirondacks est une p\u00e9riode d'effervescence alors que les r\u00e9sidents locaux se pr\u00e9parent \u00e0 un afflux de vacanciers pendant la saison estivale. Le week-end du Memorial Day marque le d\u00e9but de la saison touristique pour la plupart des entreprises du parc.<\/p>\n\n\n\n<p>Dans une r\u00e9gion o\u00f9 le tourisme est le fondement de l'activit\u00e9 \u00e9conomique, le temps et les efforts que les habitants des Adirondacks consacrent \u00e0 cette saison ne sont pas surprenants.<\/p>\n\n\n\n<p>D\u00e8s que la neige fond et que la glace dispara\u00eet, les personnes employ\u00e9es dans le secteur du tourisme s'activent de diverses mani\u00e8res : embauche et formation de nouveaux employ\u00e9s, nettoyage et ouverture de camps saisonniers, distribution de publicit\u00e9s et de brochures, r\u00e9ouverture de stands de cr\u00e8me glac\u00e9e, de motels et de marinas.<\/p>\n\n\n\n<p>Des milliers de visiteurs sont attir\u00e9s dans les Adirondacks pour se d\u00e9tendre et s'amuser dans cette r\u00e9gion s\u00e9duisante. De nombreuses exp\u00e9riences de plein air sont possibles, comme le camping, la natation, la randonn\u00e9e, la navigation de plaisance ou la relaxation au soleil.<\/p>\n\n\n\n<p>Nombreux sont ceux qui ne savent pas que cette r\u00e9gion sauvage et vierge, qui offre de nombreuses possibilit\u00e9s de loisirs de plein air, est \u00e9galement le berceau du parc \u00e0 th\u00e8me, avec une riche histoire de divertissement artificiel pour les visiteurs et les r\u00e9sidents.<\/p>\n\n\n\n<p>L'un des premiers parcs d'attractions des Adirondacks \u00e9tait \u00e0 l'origine une aire de pique-nique am\u00e9nag\u00e9e par la ligne de chemin de fer de Fonda, Johnstown et Gloversville pour attirer les clients. F.J. &amp; G. cherchait des moyens de faire revivre la ligne Gloversville et Northville, situ\u00e9e dans le coin nord-est du comt\u00e9 de Fulton, dans l'\u00c9tat de New York.<\/p>\n\n\n\n<p>Ce qui allait devenir le parc de Sacandaga, ironiquement connu sous le nom de \"Coney Island du Nord\", \u00e9tait \u00e0 l'origine un terrain de pique-nique \u00e0 louer pr\u00e8s de Northville, dans l'\u00c9tat de New York. En 1888, l'Adirondack Inn a \u00e9t\u00e9 construit avec des chambres pour 250 personnes et un ascenseur, ce qui \u00e9tait rare dans les stations des Adirondacks. Des chalets ont rapidement vu le jour autour de l'auberge.<\/p>\n\n\n\n<p>Apr\u00e8s l'incendie de 1898 qui a d\u00e9truit tous les cottages, sauf neuf, les responsables des chemins de fer ont rapidement d\u00e9blay\u00e9 les d\u00e9combres et transport\u00e9 les mat\u00e9riaux sans frais pour les r\u00e9sidents dont les biens avaient br\u00fbl\u00e9. Les hommes du chemin de fer envisageaient maintenant de r\u00e9am\u00e9nager plus qu'une simple aire de pique-nique. Les premiers ajouts seraient un th\u00e9\u00e2tre et un terrain de golf r\u00e9glementaire \u00e0 neuf trous.<\/p>\n\n\n\n<p>Ensuite, la compagnie de chemin de fer a cr\u00e9\u00e9 la Sacandaga Amusement Company, qui a construit un immense parc d'attractions avec des montagnes russes, deux carrousels, un stand de tir et une maison du plaisir. En 1901, une nouvelle aire de pique-nique a \u00e9t\u00e9 construite, ainsi qu'une tribune et un terrain de baseball qui a accueilli plus tard la New York State Baseball League. Un train miniature reliait l'\u00eele o\u00f9 se trouvait la tribune \u00e0 l'aire de jeu. Le th\u00e9\u00e2tre a attir\u00e9 des talents c\u00e9l\u00e8bres comme Al Jolson, Zazu Pitts et W.C. Fields.<\/p>\n\n\n\n<p>Cependant, de multiples incendies et un d\u00e9clin de l'utilisation du chemin de fer ont affect\u00e9 le parc de Sacandaga. La popularit\u00e9 de ce lieu de vill\u00e9giature fut de courte dur\u00e9e, de plus en plus de vacanciers d\u00e9laissant le chemin de fer au profit de la mobilit\u00e9 individuelle offerte par l'automobile. Le midway a br\u00fbl\u00e9 en 1912, suivi de la tribune en 1918.<\/p>\n\n\n\n<p>Le parc a re\u00e7u le coup de gr\u00e2ce en 1926, lorsque le Hudson River Regulating Board a condamn\u00e9 la propri\u00e9t\u00e9 en vue de la construction d'un r\u00e9servoir destin\u00e9 \u00e0 contr\u00f4ler les inondations de la rivi\u00e8re Hudson. Une grande partie des terres qui constituaient le parc Sacandaga se trouve aujourd'hui sous le r\u00e9servoir Sacandaga.<\/p>\n\n\n\n<p>Dans les ann\u00e9es 1940 et 1950, une nouvelle g\u00e9n\u00e9ration de parcs est apparue. Non ax\u00e9s sur les man\u00e8ges, ces \"parcs \u00e0 th\u00e8me\", con\u00e7us autour d'une seule id\u00e9e, \u00e9taient les premiers de leur genre dans le pays. Le tout premier \u00e9tait le p\u00f4le Nord, situ\u00e9 \u00e0 Wilmington, dans l'\u00c9tat de New York. La popularit\u00e9 instantan\u00e9e du p\u00f4le Nord est \u00e0 l'origine du d\u00e9veloppement des parcs \u00e0 th\u00e8me dans tout le pays, y compris Disneyland.<\/p>\n\n\n\n<p>En 1947, l'artiste et fabricant de jouets Arto Monaco a \u00e9t\u00e9 approch\u00e9 par un homme nomm\u00e9 Julian Reiss avec l'id\u00e9e d'un parc \u00e0 th\u00e8me con\u00e7u autour de l'histoire bien-aim\u00e9e du P\u00e8re No\u00ebl et de son atelier. Le P\u00f4le Nord a connu un succ\u00e8s imm\u00e9diat et a ouvert ses portes \u00e0 un nombre inattendu de visiteurs en 1949.<\/p>\n\n\n\n<p>La popularit\u00e9 du p\u00f4le Nord a donn\u00e9 naissance \u00e0 la ferme Old McDonald's de Reiss \u00e0 Lake Placid, dans l'\u00c9tat de New York, et au \"Land of Makebelieve\" de Monaco \u00e0 Upper Jay, dans l'\u00c9tat de New York.<\/p>\n\n\n\n<p>Au fil du temps, un certain nombre de parcs \u00e0 th\u00e8me ont fait le bonheur des visiteurs dans le parc des Adirondacks, notamment Frontier Town, une \"ville de cow-boys\" \u00e0 North Hudson, dans l'\u00c9tat de New York, qui vise \u00e0 pr\u00e9server l'histoire de la vie \u00e0 la fronti\u00e8re. Des attractions telles que Gaslight Village, \"Ghostown\", Magic Forest et The House of Frankenstein Wax Museum, toutes situ\u00e9es \u00e0 Lake George, ont contribu\u00e9 au divertissement des visiteurs des Adirondacks.<\/p>\n\n\n\n<p>Si certains de ces parcs \u00e0 th\u00e8me ont ferm\u00e9 au fil des ans, il en reste un certain nombre qui continuent d'attirer des visiteurs et de divertir petits et grands. The Great Escape, un parc \u00e0 th\u00e8me situ\u00e9 pr\u00e8s de Lake George, a incorpor\u00e9 des \u00e9l\u00e9ments de parcs qui ont ferm\u00e9, comme le Gas Light Village, Storytown et le \"Land of Makebelieve\". Le parc des Adirondacks abrite \u00e9galement le plus grand parc \u00e0 th\u00e8me aquatique de New York. L'Enchanted Forest Water Safari d'Old Forge, dans l'\u00c9tat de New York, ravit les visiteurs avec une s\u00e9rie de man\u00e8ges aquatiques et un village \u00e0 th\u00e8me qui rappelle les cr\u00e9ations originales de Monaco.<\/p>\n\n\n\n<p>L'\u00e9t\u00e9 dans les Adirondacks attire toutes sortes de personnes. De l'exploration des merveilles naturelles \u00e0 la visite d'attractions uniques cr\u00e9\u00e9es par l'homme, il existe de nombreuses fa\u00e7ons de passer du temps dans les Adirondacks. Des millions de touristes viennent chaque ann\u00e9e. C'est pourquoi les r\u00e9sidents \u00e0 l'ann\u00e9e travaillent chaque printemps pour garantir aux vacanciers de merveilleuses exp\u00e9riences estivales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Spring in the Adirondack Park is a bustling time as local residents prepare for a flood of vacationers during the summer season. Memorial Day weekend marks the beginning of the [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-927","post","type-post","status-publish","format-standard","hentry","category-adirondack-journal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>The Birth of Theme Parks in the Adirondacks | Adirondack Experience<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.theadkx.org\/fr\/la-naissance-des-parcs-a-mots-dans-les-adirondacks\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Birth of Theme Parks in the Adirondacks\" \/>\n<meta property=\"og:description\" content=\"Spring in the Adirondack Park is a bustling time as local residents prepare for a flood of vacationers during the summer season. Memorial Day weekend\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.theadkx.org\/fr\/la-naissance-des-parcs-a-mots-dans-les-adirondacks\/\" \/>\n<meta property=\"og:site_name\" content=\"Adirondack Experience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/theADKX\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-04T21:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-09T04:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg\" \/>\n<meta name=\"author\" content=\"Tara Murphy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@theadkx\" \/>\n<meta name=\"twitter:site\" content=\"@theadkx\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tara Murphy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/\"},\"author\":{\"name\":\"Tara Murphy\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/person\\\/6e347d859fdb5257a5ebe22530b1c126\"},\"headline\":\"The Birth of Theme Parks in the Adirondacks\",\"datePublished\":\"2017-04-04T21:24:00+00:00\",\"dateModified\":\"2021-04-09T04:42:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/\"},\"wordCount\":860,\"publisher\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Birth-of-Theme-Parks.jpeg\",\"articleSection\":[\"Adirondack Journal\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/\",\"name\":\"The Birth of Theme Parks in the Adirondacks | Adirondack Experience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Birth-of-Theme-Parks.jpeg\",\"datePublished\":\"2017-04-04T21:24:00+00:00\",\"dateModified\":\"2021-04-09T04:42:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Birth-of-Theme-Parks.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Birth-of-Theme-Parks.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/es\\\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.theadkx.org\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Birth of Theme Parks in the Adirondacks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#website\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/\",\"name\":\"Adirondack Experience\",\"description\":\"The Museum on Blue Mountain Lake\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.theadkx.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#organization\",\"name\":\"Adirondack Experience, The Museum on Blue Mountain Lake\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ADKX_LOGO.png\",\"contentUrl\":\"https:\\\/\\\/www.theadkx.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ADKX_LOGO.png\",\"width\":440,\"height\":276,\"caption\":\"Adirondack Experience, The Museum on Blue Mountain Lake\"},\"image\":{\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/theADKX\\\/\",\"https:\\\/\\\/x.com\\\/theadkx\",\"https:\\\/\\\/www.instagram.com\\\/theadkx\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AdirondackMuseum\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.theadkx.org\\\/#\\\/schema\\\/person\\\/6e347d859fdb5257a5ebe22530b1c126\",\"name\":\"Tara Murphy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/868d6eab9f151763f6a39a70fceb97409b7b7f745f593694c0bc7e20c9505e9d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/868d6eab9f151763f6a39a70fceb97409b7b7f745f593694c0bc7e20c9505e9d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/868d6eab9f151763f6a39a70fceb97409b7b7f745f593694c0bc7e20c9505e9d?s=96&d=mm&r=g\",\"caption\":\"Tara Murphy\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La naissance des parcs \u00e0 th\u00e8me dans les Adirondacks | Adirondack Experience","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.theadkx.org\/fr\/la-naissance-des-parcs-a-mots-dans-les-adirondacks\/","og_locale":"fr_FR","og_type":"article","og_title":"The Birth of Theme Parks in the Adirondacks","og_description":"Spring in the Adirondack Park is a bustling time as local residents prepare for a flood of vacationers during the summer season. Memorial Day weekend","og_url":"https:\/\/www.theadkx.org\/fr\/la-naissance-des-parcs-a-mots-dans-les-adirondacks\/","og_site_name":"Adirondack Experience","article_publisher":"https:\/\/www.facebook.com\/theADKX\/","article_published_time":"2017-04-04T21:24:00+00:00","article_modified_time":"2021-04-09T04:42:37+00:00","og_image":[{"url":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg","type":"","width":"","height":""}],"author":"Tara Murphy","twitter_card":"summary_large_image","twitter_creator":"@theadkx","twitter_site":"@theadkx","twitter_misc":{"\u00c9crit par":"Tara Murphy","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/#article","isPartOf":{"@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/"},"author":{"name":"Tara Murphy","@id":"https:\/\/www.theadkx.org\/#\/schema\/person\/6e347d859fdb5257a5ebe22530b1c126"},"headline":"The Birth of Theme Parks in the Adirondacks","datePublished":"2017-04-04T21:24:00+00:00","dateModified":"2021-04-09T04:42:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/"},"wordCount":860,"publisher":{"@id":"https:\/\/www.theadkx.org\/#organization"},"image":{"@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/#primaryimage"},"thumbnailUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg","articleSection":["Adirondack Journal"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/","url":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/","name":"La naissance des parcs \u00e0 th\u00e8me dans les Adirondacks | Adirondack Experience","isPartOf":{"@id":"https:\/\/www.theadkx.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/#primaryimage"},"image":{"@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/#primaryimage"},"thumbnailUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg","datePublished":"2017-04-04T21:24:00+00:00","dateModified":"2021-04-09T04:42:37+00:00","breadcrumb":{"@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/#primaryimage","url":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg","contentUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/04\/Birth-of-Theme-Parks.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.theadkx.org\/es\/el-nacimiento-de-parques-tematicos-en-los-adirondacks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.theadkx.org\/homepage\/"},{"@type":"ListItem","position":2,"name":"The Birth of Theme Parks in the Adirondacks"}]},{"@type":"WebSite","@id":"https:\/\/www.theadkx.org\/#website","url":"https:\/\/www.theadkx.org\/","name":"L'exp\u00e9rience des Adirondacks","description":"Le mus\u00e9e du lac Blue Mountain","publisher":{"@id":"https:\/\/www.theadkx.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.theadkx.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.theadkx.org\/#organization","name":"Adirondack Experience, le mus\u00e9e du lac Blue Mountain","url":"https:\/\/www.theadkx.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.theadkx.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/03\/ADKX_LOGO.png","contentUrl":"https:\/\/www.theadkx.org\/wp-content\/uploads\/2021\/03\/ADKX_LOGO.png","width":440,"height":276,"caption":"Adirondack Experience, The Museum on Blue Mountain Lake"},"image":{"@id":"https:\/\/www.theadkx.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/theADKX\/","https:\/\/x.com\/theadkx","https:\/\/www.instagram.com\/theadkx\/","https:\/\/www.youtube.com\/user\/AdirondackMuseum"]},{"@type":"Person","@id":"https:\/\/www.theadkx.org\/#\/schema\/person\/6e347d859fdb5257a5ebe22530b1c126","name":"Tara Murphy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/868d6eab9f151763f6a39a70fceb97409b7b7f745f593694c0bc7e20c9505e9d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/868d6eab9f151763f6a39a70fceb97409b7b7f745f593694c0bc7e20c9505e9d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/868d6eab9f151763f6a39a70fceb97409b7b7f745f593694c0bc7e20c9505e9d?s=96&d=mm&r=g","caption":"Tara Murphy"}}]}},"_links":{"self":[{"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/posts\/927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/comments?post=927"}],"version-history":[{"count":2,"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/posts\/927\/revisions"}],"predecessor-version":[{"id":930,"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/posts\/927\/revisions\/930"}],"wp:attachment":[{"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/media?parent=927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/categories?post=927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theadkx.org\/fr\/wp-json\/wp\/v2\/tags?post=927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}